{"id":195327,"date":"2024-11-23T22:16:50","date_gmt":"2024-11-23T20:16:50","guid":{"rendered":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg"},"modified":"2024-11-23T22:20:35","modified_gmt":"2024-11-23T20:20:35","slug":"3-enosophia-memoria-pacja-pasteta-s-prepecencem-2","status":"inherit","type":"attachment","link":"https:\/\/travel-advisor.eu\/en\/3-enosophia-memoria-pacja-pasteta-s-prepecencem-2\/","title":{"rendered":"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem - Travel Advisor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem - Travel Advisor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"Travel Advisor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Savjetnik-za-putovanja-1268106453311008\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-23T20:20:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"999\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg\",\"url\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg\",\"name\":\"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem - Travel Advisor\",\"isPartOf\":{\"@id\":\"https:\/\/travel-advisor.eu\/#website\"},\"datePublished\":\"2024-11-23T20:16:50+00:00\",\"dateModified\":\"2024-11-23T20:20:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\/\/travel-advisor.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/travel-advisor.eu\/#website\",\"url\":\"https:\/\/travel-advisor.eu\/\",\"name\":\"Travel Advisor\",\"description\":\"Magazin u kojem putnici pi\u0161u za putnike\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/travel-advisor.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem - Travel Advisor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","og_locale":"en_US","og_type":"article","og_title":"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem - Travel Advisor","og_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","og_site_name":"Travel Advisor","article_publisher":"https:\/\/www.facebook.com\/Savjetnik-za-putovanja-1268106453311008\/","article_modified_time":"2024-11-23T20:20:35+00:00","og_image":[{"width":999,"height":667,"url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","name":"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem - Travel Advisor","isPartOf":{"@id":"https:\/\/travel-advisor.eu\/#website"},"datePublished":"2024-11-23T20:16:50+00:00","dateModified":"2024-11-23T20:20:35+00:00","breadcrumb":{"@id":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/travel-advisor.eu\/"},{"@type":"ListItem","position":2,"name":"3-Enosophia Memoria, Pac\u030cja pas\u030cteta s prepec\u030cencem"}]},{"@type":"WebSite","@id":"https:\/\/travel-advisor.eu\/#website","url":"https:\/\/travel-advisor.eu\/","name":"Travel Advisor","description":"Magazin u kojem putnici pi\u0161u za putnike","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travel-advisor.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg'><img fetchpriority=\"high\" decoding=\"async\" width=\"999\" height=\"667\" src=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg\" class=\"attachment-medium size-medium\" alt=\"Enosphia\" srcset=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg 999w, https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-768x513.jpeg 768w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Enosphia","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":999,"height":667,"file":"2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","filesize":69371,"sizes":{"medium_large":{"file":"3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-768x513.jpeg","width":768,"height":513,"filesize":44131,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-768x513.jpeg"},"qi_addons_for_elementor_image_size_square":{"file":"3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-650x650.jpeg","width":650,"height":650,"filesize":45515,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-650x650.jpeg"},"qi_addons_for_elementor_image_size_landscape":{"file":"3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-999x650.jpeg","width":999,"height":650,"filesize":69452,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-999x650.jpeg"},"qi_addons_for_elementor_image_size_portrait":{"file":"3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-650x667.jpeg","width":650,"height":667,"filesize":50715,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem-650x667.jpeg"},"full":{"file":"3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","width":999,"height":667,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2024\/11\/3-Enosophia-Memoria-Pacja-pasteta-s-prepecencem.jpeg","_links":{"self":[{"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/media\/195327"}],"collection":[{"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/comments?post=195327"}]}}