{"id":200468,"date":"2025-05-28T11:15:57","date_gmt":"2025-05-28T09:15:57","guid":{"rendered":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg"},"modified":"2025-05-28T11:16:40","modified_gmt":"2025-05-28T09:16:40","slug":"radevic-vinarija-crna-gora-14-2","status":"inherit","type":"attachment","link":"https:\/\/travel-advisor.eu\/en\/radevic-vinarija-crna-gora-14-2\/","title":{"rendered":"RADEVI\u0106 vinarija Crna Gora (14)"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RADEVI\u0106 vinarija Crna Gora (14) - Travel Advisor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RADEVI\u0106 vinarija Crna Gora (14) - Travel Advisor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"Travel Advisor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Savjetnik-za-putovanja-1268106453311008\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T09:16:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg\",\"url\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg\",\"name\":\"RADEVI\u0106 vinarija Crna Gora (14) - Travel Advisor\",\"isPartOf\":{\"@id\":\"https:\/\/travel-advisor.eu\/#website\"},\"datePublished\":\"2025-05-28T09:15:57+00:00\",\"dateModified\":\"2025-05-28T09:16:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\/\/travel-advisor.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RADEVI\u0106 vinarija Crna Gora (14)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/travel-advisor.eu\/#website\",\"url\":\"https:\/\/travel-advisor.eu\/\",\"name\":\"Travel Advisor\",\"description\":\"Magazin u kojem putnici pi\u0161u za putnike\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/travel-advisor.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RADEVI\u0106 vinarija Crna Gora (14) - Travel Advisor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg","og_locale":"en_US","og_type":"article","og_title":"RADEVI\u0106 vinarija Crna Gora (14) - Travel Advisor","og_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg","og_site_name":"Travel Advisor","article_publisher":"https:\/\/www.facebook.com\/Savjetnik-za-putovanja-1268106453311008\/","article_modified_time":"2025-05-28T09:16:40+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg","url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg","name":"RADEVI\u0106 vinarija Crna Gora (14) - Travel Advisor","isPartOf":{"@id":"https:\/\/travel-advisor.eu\/#website"},"datePublished":"2025-05-28T09:15:57+00:00","dateModified":"2025-05-28T09:16:40+00:00","breadcrumb":{"@id":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/travel-advisor.eu\/"},{"@type":"ListItem","position":2,"name":"RADEVI\u0106 vinarija Crna Gora (14)"}]},{"@type":"WebSite","@id":"https:\/\/travel-advisor.eu\/#website","url":"https:\/\/travel-advisor.eu\/","name":"Travel Advisor","description":"Magazin u kojem putnici pi\u0161u za putnike","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travel-advisor.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg'><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg\" class=\"attachment-medium size-medium\" alt=\"Crna Gora vina\" srcset=\"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg 800w, https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14-768x512.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Crna Gora vina","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":533,"file":"2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg","filesize":107938,"sizes":{"medium_large":{"file":"RADEVIC-vinarija-Crna-Gora-14-768x512.jpeg","width":768,"height":512,"filesize":88125,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14-768x512.jpeg"},"qi_addons_for_elementor_image_size_square":{"file":"RADEVIC-vinarija-Crna-Gora-14-650x533.jpeg","width":650,"height":533,"filesize":87448,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14-650x533.jpeg"},"qi_addons_for_elementor_image_size_portrait":{"file":"RADEVIC-vinarija-Crna-Gora-14-650x533.jpeg","width":650,"height":533,"filesize":87448,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14-650x533.jpeg"},"full":{"file":"RADEVIC-vinarija-Crna-Gora-14.jpeg","width":800,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg"}},"image_meta":{"aperture":"11","credit":"","camera":"Canon EOS 100D","caption":"","created_timestamp":"1471609001","copyright":"","focal_length":"29","iso":"100","shutter_speed":"0.003125","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/travel-advisor.eu\/wp-content\/uploads\/2025\/05\/RADEVIC-vinarija-Crna-Gora-14.jpeg","_links":{"self":[{"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/media\/200468"}],"collection":[{"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travel-advisor.eu\/en\/wp-json\/wp\/v2\/comments?post=200468"}]}}